{"id":26274,"date":"2023-10-03T11:41:50","date_gmt":"2023-10-03T10:41:50","guid":{"rendered":"https:\/\/reedmackay.com\/a-masterclass-in-group-travel-for-thousands-case-study"},"modified":"2024-04-18T13:47:45","modified_gmt":"2024-04-18T12:47:45","slug":"a-masterclass-in-group-travel-for-thousands-case-study","status":"publish","type":"post","link":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study","title":{"rendered":"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas"},"content":{"rendered":"\n<p><strong>Le d\u00e9fi : <\/strong>L&rsquo;organisation sans faille du voyage de plus de 2 000 participants de la Su\u00e8de \u00e0 la Cor\u00e9e du Sud pour le Jamboree Scout Mondial implique des comp\u00e9tences et une exp\u00e9rience logistiques de premier ordre. Cependant, lorsque des conditions m\u00e9t\u00e9orologiques extr\u00eames et des passeports perdus s&rsquo;y ajoutent, toute une s\u00e9rie de comp\u00e9tences en mati\u00e8re de gestion de crise sont \u00e9galement requises.<\/p>\n\n<p><strong>La solution : <\/strong> <a href=\"https:\/\/www.resia.se\/business\/business-travel\" target=\"_blank\" rel=\"noreferrer noopener\">Resia<\/a>, soci\u00e9t\u00e9 de gestion d&rsquo;\u00e9v\u00e9nements, de congr\u00e8s et de voyages d&rsquo;affaires bas\u00e9e \u00e0 G\u00f6teborg &#8211; qui a rejoint la famille Reed &amp; Mackay en juin &#8211; a utilis\u00e9 ses relations bien \u00e9tablies dans l&rsquo;industrie du voyage pour g\u00e9rer ces d\u00e9fis de mani\u00e8re efficace, en aidant \u00e0 r\u00e9aliser le voyage d&rsquo;une vie pour un grand nombre de personnes.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-46738\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-1-1024x768.jpeg 1024w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-1-300x225.jpeg 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-1-768x576.jpeg 768w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-1-1536x1152.jpeg 1536w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-1.jpeg 2016w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dit photo : Scouts Su\u00e8de<\/figcaption><\/figure>\n\n<p>Le 25e <a href=\"https:\/\/www.scout.org\/what-we-do\/world-scout-events\/world-scout-jamboree\" target=\"_blank\" rel=\"noreferrer noopener\">Jamboree scout mondial<\/a>, qui s&rsquo;est d\u00e9roul\u00e9 en ao\u00fbt, a \u00e9t\u00e9 l&rsquo;un des plus grands \u00e9v\u00e9nements \u00e9ducatifs en plein air pour les jeunes \u00e2g\u00e9s de 14 \u00e0 17 ans.<\/p>\n\n<p>Des dizaines de milliers de scouts du monde entier se sont r\u00e9unis pour camper en plein air et participer \u00e0 des activit\u00e9s. Ce fut une exp\u00e9rience de voyage incontournable, avec la possibilit\u00e9 de se faire de nouveaux amis, de d\u00e9couvrir d&rsquo;autres cultures et de d\u00e9velopper des comp\u00e9tences en mati\u00e8re de leadership. Le bon d\u00e9roulement de l&rsquo;ensemble des op\u00e9rations \u00e9tait essentiel.<\/p>\n\n<p>L&rsquo;\u00e9v\u00e9nement de cette ann\u00e9e &#8211; le Jamboree se tient tous les quatre ans dans des destinations diff\u00e9rentes &#8211; est la troisi\u00e8me fois que Resia organise le voyage du contingent scout su\u00e9dois. Apr\u00e8s avoir travaill\u00e9 pour la premi\u00e8re fois avec l&rsquo;organisation en 2015, Resia a accueilli cette ann\u00e9e 2 100 participants pour se rendre de la Su\u00e8de \u00e0 la Cor\u00e9e du Sud.<\/p>\n\n<p>En outre, Resia a apport\u00e9 son soutien en organisant des excursions suppl\u00e9mentaires autour de la destination pendant et apr\u00e8s l&rsquo;\u00e9v\u00e9nement. La planification de l&rsquo;\u00e9v\u00e9nement a d\u00e9but\u00e9 en 2021, en raison du grand nombre de personnes \u00e0 transporter.<\/p>\n\n<p>\u00ab\u00a0Nous avons d\u00e9sign\u00e9 un chef de projet \u00e0 temps plein pour cet \u00e9v\u00e9nement, soutenu par quelques autres membres de l&rsquo;\u00e9quipe en cas de besoin\u00a0\u00bb, explique Niclas Levin, Senior Manager Groups &amp; Meetings de Resia.<\/p>\n\n<p>\u00ab\u00a0Nous avons r\u00e9serv\u00e9 49 groupes &#8211; avec environ 40 scouts et quatre responsables scouts par groupe &#8211; sur des vols internationaux aupr\u00e8s de neuf compagnies a\u00e9riennes diff\u00e9rentes. Nous avons \u00e9galement r\u00e9serv\u00e9 environ 200 autres billets individuels avec des exigences diff\u00e9rentes en termes de date et de destination. De plus, nous avons d\u00fb organiser des r\u00e9gimes alimentaires sp\u00e9ciaux pour plus de 400 personnes\u00a0\u00bb.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>RELEVER LES D\u00c9FIS AVANT LE D\u00c9PART<\/strong><\/h2>\n\n<p>Il s&rsquo;agit d&rsquo;un exploit d&rsquo;organisation de premier ordre. Resia a d\u00fb veiller \u00e0 ce que les participants voyagent pendant huit jours afin que tous puissent participer au camp et aux activit\u00e9s. Tous les scouts devaient vivre le m\u00eame programme. En outre, comme les scouts su\u00e9dois voulaient pr\u00e9senter le jeu traditionnel de Kubb &#8211; qui comprend de lourds blocs de bois &#8211; \u00e0 leurs homologues du monde entier, Resia a travaill\u00e9 avec les compagnies a\u00e9riennes pour s&rsquo;assurer qu&rsquo;ils pouvaient apporter le jeu dans les bagages.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-46745\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-1-1024x768.jpeg 1024w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-1-300x225.jpeg 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-1-768x576.jpeg 768w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-1-1536x1152.jpeg 1536w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-1.jpeg 2016w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dit photo : Scouts Su\u00e8de<\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\"><strong>L&rsquo;IMPORTANCE DES PARTENARIATS DANS LE DOMAINE DES VOYAGES<\/strong><\/h2>\n\n<p>\u00ab\u00a0Le choix du bon partenaire DMC \u00e9tait crucial, car nous n&rsquo;\u00e9tions pas sur le terrain pour cet \u00e9v\u00e9nement particulier et nous devions pouvoir r\u00e9server en toute confiance\u00a0\u00bb, poursuit M. Levin. \u00ab\u00a0Une soci\u00e9t\u00e9 de repr\u00e9sentation DMC avec laquelle nous travaillons en Su\u00e8de, Travel Collection, a recommand\u00e9 <a href=\"https:\/\/krhospitality.co\/\" target=\"_blank\" rel=\"noreferrer noopener\">KR Hospitality &amp; Events<\/a>.<\/p>\n\n<p>\u00ab\u00a0Resia s&rsquo;est rendue en Cor\u00e9e du Sud pour les rencontrer. Nous avons choisi de travailler avec cette agence en raison de sa grande exp\u00e9rience des \u00e9v\u00e9nements de grande envergure, y compris les Jeux olympiques. De plus, le propri\u00e9taire de l&rsquo;entreprise avait v\u00e9cu en Europe et comprenait les exigences et la mentalit\u00e9 du groupe su\u00e9dois en mati\u00e8re de voyages.<\/p>\n\n<p>Le CGM a organis\u00e9 le transport terrestre, y compris 92 navettes vers et depuis l&rsquo;a\u00e9roport et les h\u00f4tels, ainsi que 182 autres bus pour les excursions du programme. Les scouts su\u00e9dois ont \u00e9t\u00e9 invit\u00e9s \u00e0 visiter diverses zones de S\u00e9oul, notamment la zone d\u00e9militaris\u00e9e et l&rsquo;observatoire Odusan, ainsi que la ville de Busan.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>DES SOLUTIONS DE VOYAGE EN CAS DE CONDITIONS M\u00c9T\u00c9OROLOGIQUES EXTR\u00caMES<\/strong><\/h2>\n\n<p>M\u00eame un \u00e9v\u00e9nement bien planifi\u00e9 ne peut pr\u00e9voir des facteurs impr\u00e9visibles tels que des conditions m\u00e9t\u00e9orologiques extr\u00eames. Pendant le Jamboree, il y a eu non pas un, mais deux \u00e9v\u00e9nements m\u00e9t\u00e9orologiques difficiles \u00e0 affronter. D&rsquo;une part, les temp\u00e9ratures \u00e9lev\u00e9es et, d&rsquo;autre part, la menace d&rsquo;un typhon qui s&rsquo;abattrait sur le camping. Les scouts ont d\u00fb rapidement d\u00e9cider de fermer le camp et de d\u00e9placer les 40 000 participants.<\/p>\n\n<p>\u00ab\u00a0Le plan d&rsquo;urgence a \u00e9t\u00e9 mis en place gr\u00e2ce \u00e0 une collaboration avec le gouvernement sud-cor\u00e9en et de nombreux fournisseurs locaux\u00a0\u00bb, explique M. Levin.<\/p>\n\n<p>\u00ab\u00a0En une seule journ\u00e9e, 1 000 bus ont pris en charge les participants et les ont emmen\u00e9s dans 130 lieux d&rsquo;h\u00e9bergement diff\u00e9rents \u00e0 S\u00e9oul. Nous sommes rest\u00e9s en contact avec les chefs scouts et les fournisseurs sur le nouveau site. Cette mesure visait \u00e0 garantir que le reste du programme puisse se d\u00e9rouler comme pr\u00e9vu. Nous avons b\u00e9n\u00e9fici\u00e9 d&rsquo;un excellent service \u00e0 la client\u00e8le de la part de notre DMC, qui a \u00e9t\u00e9 formidable.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-2-1024x768.jpeg\" alt=\"\" class=\"wp-image-46752\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-2-1024x768.jpeg 1024w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-2-300x225.jpeg 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-2-768x576.jpeg 768w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-2-1536x1152.jpeg 1536w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/Credit-Scouts-Sweden-2-2.jpeg 2016w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dit photo : Scouts Su\u00e8de<\/figcaption><\/figure>\n\n<p>Des canaux de communication clairs sont un \u00e9l\u00e9ment essentiel de la strat\u00e9gie logistique de Resia lorsqu&rsquo;il s&rsquo;agit de planifier des programmes de voyage \u00e0 grande \u00e9chelle. M. Levin explique qu&rsquo;ils ont des fils de conversation distincts sur le transport a\u00e9rien, le transport terrestre, les h\u00f4tels, les excursions et la m\u00e9t\u00e9o.<\/p>\n\n<p>\u00ab\u00a0Pendant tout ce temps, nous nous tenons au courant de tout ce qui concerne l&rsquo;\u00e9v\u00e9nement\u00a0\u00bb, explique-t-il. \u00ab\u00a0Nous avions alors un plan de secours au cas o\u00f9 nous devrions changer les arrangements de voyage pour la derni\u00e8re \u00e9tape du voyage, car ils avaient \u00e9t\u00e9 d\u00e9plac\u00e9s \u00e0 S\u00e9oul (en raison des conditions m\u00e9t\u00e9orologiques). Nous avons d\u00fb changer les heures de d\u00e9part des bus qui emmenaient les scouts \u00e0 Busan\u00a0\u00bb.<\/p>\n\n<p>En outre, lors du voyage de retour, Resia a d\u00fb s&rsquo;occuper de plusieurs passeports perdus par la d\u00e9l\u00e9gation su\u00e9doise. \u00ab\u00a0Nous avons travaill\u00e9 en \u00e9troite collaboration avec les compagnies a\u00e9riennes et les responsables des scouts ont contact\u00e9 l&rsquo;ambassade de Su\u00e8de \u00e0 S\u00e9oul pour obtenir des copies des passeports et nous n&rsquo;avons pas eu \u00e0 annuler de vols\u00a0\u00bb, ajoute M. Levin.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>UN R\u00c9SULTAT POSITIF<\/strong><\/h2>\n\n<p>Les 2 100 participants su\u00e9dois ont tous voyag\u00e9 sans encombre vers et depuis la Cor\u00e9e du Sud, bien qu&rsquo;ils aient \u00e9t\u00e9 confront\u00e9s \u00e0 un certain nombre de d\u00e9fis ext\u00e9rieurs. Oscar Sund\u00e5s, le principal contact de Resia chez les scouts su\u00e9dois, a salu\u00e9 le grand succ\u00e8s de l&rsquo;\u00e9v\u00e9nement. \u00ab\u00a0Les participants ont eu l&rsquo;occasion de rencontrer de nouveaux amis du monde entier, de participer \u00e0 des activit\u00e9s et de d\u00e9couvrir la Cor\u00e9e du Sud\u00a0\u00bb, explique-t-il. \u00ab\u00a0Gr\u00e2ce \u00e0 l&rsquo;excellente organisation du transport de nos groupes su\u00e9dois vers et depuis le Jamboree, tout s&rsquo;est bien pass\u00e9, m\u00eame avec le changement de d\u00e9cor.<\/p>\n\n<p><a href=\"https:\/\/reedmackay.com\/contact\">Prendre contact<\/a><\/p>\n\n<p>Envoyez un courriel \u00e0 hello@reedandmackay.com pour discuter de tous vos besoins en mati\u00e8re de gestion de r\u00e9unions et d&rsquo;\u00e9v\u00e9nements.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9fi : L&rsquo;organisation sans faille du voyage de plus de 2 000 participants de la Su\u00e8de \u00e0 la Cor\u00e9e du Sud pour le Jamboree Scout Mondial implique des comp\u00e9tences et une exp\u00e9rience logistiques de premier ordre. Cependant, lorsque des conditions m\u00e9t\u00e9orologiques extr\u00eames et des passeports perdus s&rsquo;y ajoutent, toute une s\u00e9rie de comp\u00e9tences en&hellip;&nbsp;<a href=\"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":3575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[214],"tags":[215,176],"class_list":["post-26274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cas-utilisateurs-fr","tag-group-travel-fr","tag-travel-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas<\/title>\n<meta name=\"description\" content=\"\u00c9tude de cas sur les voyages de groupes d&#039;entreprises o\u00f9 nous avons organis\u00e9 sans probl\u00e8me le voyage de plus de 2 000 participants de la Su\u00e8de \u00e0 la Cor\u00e9e du Sud...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas\" \/>\n<meta property=\"og:description\" content=\"\u00c9tude de cas sur les voyages de groupes d&#039;entreprises o\u00f9 nous avons organis\u00e9 sans probl\u00e8me le voyage de plus de 2 000 participants de la Su\u00e8de \u00e0 la Cor\u00e9e du Sud...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study\" \/>\n<meta property=\"og:site_name\" content=\"Reed &amp; Mackay\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-03T10:41:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T12:47:45+00:00\" \/>\n<meta name=\"author\" content=\"sjtechnical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas\" \/>\n<meta name=\"twitter:description\" content=\"\u00c9tude de cas sur les voyages de groupes d&#039;entreprises o\u00f9 nous avons organis\u00e9 sans probl\u00e8me le voyage de plus de 2 000 participants de la Su\u00e8de \u00e0 la Cor\u00e9e du Sud...\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"sjtechnical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study\"},\"author\":{\"name\":\"sjtechnical\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr#\\\/schema\\\/person\\\/e19bbdca65476dcbecbbebc528743162\"},\"headline\":\"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas\",\"datePublished\":\"2023-10-03T10:41:50+00:00\",\"dateModified\":\"2024-04-18T12:47:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study\"},\"wordCount\":1327,\"publisher\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reedmackay.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Reed-and-Mackay-Corporate-Events-Management-1080-x-768-px-2.jpg\",\"keywords\":[\"Group Travel\",\"Travel\"],\"articleSection\":[\"Etude de cas\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study\",\"url\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study\",\"name\":\"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reedmackay.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Reed-and-Mackay-Corporate-Events-Management-1080-x-768-px-2.jpg\",\"datePublished\":\"2023-10-03T10:41:50+00:00\",\"dateModified\":\"2024-04-18T12:47:45+00:00\",\"description\":\"\u00c9tude de cas sur les voyages de groupes d'entreprises o\u00f9 nous avons organis\u00e9 sans probl\u00e8me le voyage de plus de 2 000 participants de la Su\u00e8de \u00e0 la Cor\u00e9e du Sud...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study#primaryimage\",\"url\":\"https:\\\/\\\/reedmackay.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Reed-and-Mackay-Corporate-Events-Management-1080-x-768-px-2.jpg\",\"contentUrl\":\"https:\\\/\\\/reedmackay.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Reed-and-Mackay-Corporate-Events-Management-1080-x-768-px-2.jpg\",\"width\":1080,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/a-masterclass-in-group-travel-for-thousands-case-study#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/reedmackay.com\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr#website\",\"url\":\"https:\\\/\\\/reedmackay.com\\\/fr\",\"name\":\"Reed & Mackay\",\"description\":\"Reed and Mackay Travel and Events Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/reedmackay.com\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr#organization\",\"name\":\"Reed & Mackay\",\"url\":\"https:\\\/\\\/reedmackay.com\\\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/reedmackay.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/RM-Horz-Logo-Colour@2x.png\",\"contentUrl\":\"https:\\\/\\\/reedmackay.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/RM-Horz-Logo-Colour@2x.png\",\"width\":2107,\"height\":411,\"caption\":\"Reed & Mackay\"},\"image\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/fr#\\\/schema\\\/person\\\/e19bbdca65476dcbecbbebc528743162\",\"name\":\"sjtechnical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5d8deff8dc3efd21c837c996838b2e50c65a4ac9f75cec20f20c978d7387548?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5d8deff8dc3efd21c837c996838b2e50c65a4ac9f75cec20f20c978d7387548?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5d8deff8dc3efd21c837c996838b2e50c65a4ac9f75cec20f20c978d7387548?s=96&d=mm&r=g\",\"caption\":\"sjtechnical\"},\"sameAs\":[\"https:\\\/\\\/reedmackay.com\"],\"url\":\"https:\\\/\\\/reedmackay.com\\\/fr\\\/author\\\/sjtechnical\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas","description":"\u00c9tude de cas sur les voyages de groupes d'entreprises o\u00f9 nous avons organis\u00e9 sans probl\u00e8me le voyage de plus de 2 000 participants de la Su\u00e8de \u00e0 la Cor\u00e9e du Sud...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study","og_locale":"fr_FR","og_type":"article","og_title":"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas","og_description":"\u00c9tude de cas sur les voyages de groupes d'entreprises o\u00f9 nous avons organis\u00e9 sans probl\u00e8me le voyage de plus de 2 000 participants de la Su\u00e8de \u00e0 la Cor\u00e9e du Sud...","og_url":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study","og_site_name":"Reed &amp; Mackay","article_published_time":"2023-10-03T10:41:50+00:00","article_modified_time":"2024-04-18T12:47:45+00:00","author":"sjtechnical","twitter_card":"summary_large_image","twitter_title":"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas","twitter_description":"\u00c9tude de cas sur les voyages de groupes d'entreprises o\u00f9 nous avons organis\u00e9 sans probl\u00e8me le voyage de plus de 2 000 participants de la Su\u00e8de \u00e0 la Cor\u00e9e du Sud...","twitter_misc":{"\u00c9crit par":"sjtechnical","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study#article","isPartOf":{"@id":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study"},"author":{"name":"sjtechnical","@id":"https:\/\/reedmackay.com\/fr#\/schema\/person\/e19bbdca65476dcbecbbebc528743162"},"headline":"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas","datePublished":"2023-10-03T10:41:50+00:00","dateModified":"2024-04-18T12:47:45+00:00","mainEntityOfPage":{"@id":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study"},"wordCount":1327,"publisher":{"@id":"https:\/\/reedmackay.com\/fr#organization"},"image":{"@id":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study#primaryimage"},"thumbnailUrl":"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Events-Management-1080-x-768-px-2.jpg","keywords":["Group Travel","Travel"],"articleSection":["Etude de cas"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study","url":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study","name":"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas","isPartOf":{"@id":"https:\/\/reedmackay.com\/fr#website"},"primaryImageOfPage":{"@id":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study#primaryimage"},"image":{"@id":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study#primaryimage"},"thumbnailUrl":"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Events-Management-1080-x-768-px-2.jpg","datePublished":"2023-10-03T10:41:50+00:00","dateModified":"2024-04-18T12:47:45+00:00","description":"\u00c9tude de cas sur les voyages de groupes d'entreprises o\u00f9 nous avons organis\u00e9 sans probl\u00e8me le voyage de plus de 2 000 participants de la Su\u00e8de \u00e0 la Cor\u00e9e du Sud...","breadcrumb":{"@id":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study#primaryimage","url":"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Events-Management-1080-x-768-px-2.jpg","contentUrl":"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Events-Management-1080-x-768-px-2.jpg","width":1080,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/reedmackay.com\/fr\/a-masterclass-in-group-travel-for-thousands-case-study#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/reedmackay.com\/fr"},{"@type":"ListItem","position":2,"name":"Un cours magistral sur les voyages de groupe pour des milliers de personnes : \u00c9tude de cas"}]},{"@type":"WebSite","@id":"https:\/\/reedmackay.com\/fr#website","url":"https:\/\/reedmackay.com\/fr","name":"Reed & Mackay","description":"Reed and Mackay Travel and Events Management","publisher":{"@id":"https:\/\/reedmackay.com\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reedmackay.com\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/reedmackay.com\/fr#organization","name":"Reed & Mackay","url":"https:\/\/reedmackay.com\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/reedmackay.com\/fr#\/schema\/logo\/image\/","url":"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/07\/RM-Horz-Logo-Colour@2x.png","contentUrl":"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/07\/RM-Horz-Logo-Colour@2x.png","width":2107,"height":411,"caption":"Reed & Mackay"},"image":{"@id":"https:\/\/reedmackay.com\/fr#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/reedmackay.com\/fr#\/schema\/person\/e19bbdca65476dcbecbbebc528743162","name":"sjtechnical","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f5d8deff8dc3efd21c837c996838b2e50c65a4ac9f75cec20f20c978d7387548?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5d8deff8dc3efd21c837c996838b2e50c65a4ac9f75cec20f20c978d7387548?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5d8deff8dc3efd21c837c996838b2e50c65a4ac9f75cec20f20c978d7387548?s=96&d=mm&r=g","caption":"sjtechnical"},"sameAs":["https:\/\/reedmackay.com"],"url":"https:\/\/reedmackay.com\/fr\/author\/sjtechnical"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/reedmackay.com\/fr\/wp-json\/wp\/v2\/posts\/26274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reedmackay.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reedmackay.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reedmackay.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reedmackay.com\/fr\/wp-json\/wp\/v2\/comments?post=26274"}],"version-history":[{"count":0,"href":"https:\/\/reedmackay.com\/fr\/wp-json\/wp\/v2\/posts\/26274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reedmackay.com\/fr\/wp-json\/wp\/v2\/media\/3575"}],"wp:attachment":[{"href":"https:\/\/reedmackay.com\/fr\/wp-json\/wp\/v2\/media?parent=26274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reedmackay.com\/fr\/wp-json\/wp\/v2\/categories?post=26274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reedmackay.com\/fr\/wp-json\/wp\/v2\/tags?post=26274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}