{"id":17642,"date":"2023-12-13T15:06:32","date_gmt":"2023-12-13T15:06:32","guid":{"rendered":"https:\/\/reedmackay.com\/seguridad-del-viajero"},"modified":"2024-01-26T10:41:46","modified_gmt":"2024-01-26T10:41:46","slug":"seguridad-para-los-viajeros","status":"publish","type":"page","link":"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros","title":{"rendered":"Seguridad para los viajeros"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"17642\" class=\"elementor elementor-17642 elementor-3161\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e2dd6e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2dd6e8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef17aeb\" data-id=\"ef17aeb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0d5aa00 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0d5aa00\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-b2cd8ca\" data-id=\"b2cd8ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ded5c6c elementor-widget elementor-widget-image\" data-id=\"ded5c6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/gestionar-reservas\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-6-2.png\" class=\"attachment-large size-large wp-image-4415\" alt=\"\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-6-2.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-6-2-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7182943 elementor-widget elementor-widget-heading\" data-id=\"7182943\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reedmackay.com\/es\/gestionar-reservas\">Gesti\u00f3n de reservas<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-72d059b\" data-id=\"72d059b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74093ee elementor-widget elementor-widget-image\" data-id=\"74093ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-15.png\" class=\"attachment-large size-large wp-image-4420\" alt=\"\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-15.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-15-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c17e4d elementor-widget elementor-widget-heading\" data-id=\"6c17e4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros\">Seguridad para los viajeros<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-bf01134\" data-id=\"bf01134\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5ae760 elementor-widget elementor-widget-image\" data-id=\"d5ae760\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/aprobaciones\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-9-1.png\" class=\"attachment-large size-large wp-image-4375\" alt=\"\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-9-1.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-9-1-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8297bbd elementor-widget elementor-widget-heading\" data-id=\"8297bbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reedmackay.com\/es\/aprobaciones\">Aprobaciones sencillas<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-119e8a8\" data-id=\"119e8a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-674599e elementor-widget elementor-widget-image\" data-id=\"674599e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/gestion-de-gastos\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-11-1.png\" class=\"attachment-large size-large wp-image-4385\" alt=\"\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-11-1.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-11-1-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e67929 elementor-widget elementor-widget-heading\" data-id=\"3e67929\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reedmackay.com\/es\/gestion-de-gastos\">Gesti\u00f3n de gastos<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-b41ff7d\" data-id=\"b41ff7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c688a29 elementor-widget elementor-widget-image\" data-id=\"c688a29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/informacion-detallada\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-8-2.png\" class=\"attachment-large size-large wp-image-4370\" alt=\"\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-8-2.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-8-2-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-096ea4f elementor-widget elementor-widget-heading\" data-id=\"096ea4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reedmackay.com\/es\/informacion-detallada\">Informaci\u00f3n detallada<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-a6df58d\" data-id=\"a6df58d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9527c47 elementor-widget elementor-widget-image\" data-id=\"9527c47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/sobre-la-marcha\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-4-2.png\" class=\"attachment-large size-large wp-image-4405\" alt=\"\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-4-2.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-4-2-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-775eb48 elementor-widget elementor-widget-heading\" data-id=\"775eb48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/reedmackay.com\/es\/sobre-la-marcha\">Aplicaci\u00f3n m\u00f3vil<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a1a1dc elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"5a1a1dc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a0dd23\" data-id=\"4a0dd23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e4558a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4558a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e7958ba\" data-id=\"e7958ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fa0f1f elementor-widget elementor-widget-heading\" data-id=\"3fa0f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Seguridad para los viajeros<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58c8166 elementor-widget elementor-widget-heading\" data-id=\"58c8166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Localice a sus viajeros en cualquier momento, dondequiera que est\u00e9n. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8562a98 elementor-widget elementor-widget-text-editor\" data-id=\"8562a98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le ayudamos a cuidar a su personal mediante el uso de una tecnolog\u00eda l\u00edder a nivel global respaldada por un servicio de emergencia en viajes.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddba0a7 elementor-widget elementor-widget-spacer\" data-id=\"ddba0a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6990d5b elementor-align-center elementor-widget elementor-widget-global elementor-global-18731 elementor-global-1371 elementor-widget-button\" data-id=\"6990d5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/reedmackay.com\/es\/consulta-de-nuevo-negocio\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hable con un experto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ed3e95 elementor-align-center elementor-widget__width-initial elementor-widget elementor-widget-global elementor-global-18516 elementor-global-5048 elementor-widget-button\" data-id=\"9ed3e95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/reedmackay.com\/es\/solicita-una-demostracion\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicite una demostraci\u00f3n gratuita<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c5237f elementor-widget elementor-widget-text-editor\" data-id=\"5c5237f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un <strong>mapa integrado e interactivo<\/strong>, con los riesgos <strong>clasificados por c\u00f3digo de colores<\/strong>, le permite ver en tiempo <strong>real la ubicaci\u00f3n<\/strong> de cada viajero<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-527cfd1 elementor-widget elementor-widget-text-editor\" data-id=\"527cfd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reciba <strong>alertas por correo electr\u00f3nico<\/strong> o <strong>notificaciones autom\u00e1ticas<\/strong> dentro de la aplicaci\u00f3n si se produce cualquier alteraci\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2e8ea1 elementor-widget elementor-widget-text-editor\" data-id=\"d2e8ea1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los viajeros tambi\u00e9n pueden <strong>registrarse<\/strong> para dar a conocer su ubicaci\u00f3n en caso de emergencia.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09042f3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"09042f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-17e2328 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"17e2328\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-39ec919\" data-id=\"39ec919\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa73801 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"aa73801\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comprometidos con una atenci\u00f3n excepcional<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29fbd77 elementor-widget elementor-widget-text-editor\" data-id=\"29fbd77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nada nos importa m\u00e1s que la seguridad de los suyos. Nuestra unidad de gesti\u00f3n de incidentes 24\/7 est\u00e1 lista para intervenir al instante, asegurando la seguridad de sus viajeros. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-63e5049 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63e5049\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-64143d2\" data-id=\"64143d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5534aaa elementor-widget elementor-widget-image\" data-id=\"5534aaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-1.png\" class=\"attachment-large size-large wp-image-5539\" alt=\"\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-1.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-1-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0258cc6\" data-id=\"0258cc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59b35a1 elementor-widget elementor-widget-text-editor\" data-id=\"59b35a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Retrasos y cancelaciones de viaje<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-78b50c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78b50c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-61ce1a6\" data-id=\"61ce1a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d832f7f elementor-widget elementor-widget-image\" data-id=\"d832f7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-2.png\" class=\"attachment-large size-large wp-image-5524\" alt=\"\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-2.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-2-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c5b8fd4\" data-id=\"c5b8fd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e2bff3 elementor-widget elementor-widget-text-editor\" data-id=\"5e2bff3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alertas meteorol\u00f3gicas<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b698138 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b698138\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a358508\" data-id=\"a358508\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a40ba7 elementor-widget elementor-widget-image\" data-id=\"7a40ba7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-3.png\" class=\"attachment-large size-large wp-image-5529\" alt=\"\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-3.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-3-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a231817\" data-id=\"a231817\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f53e7dd elementor-widget elementor-widget-text-editor\" data-id=\"f53e7dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Disturbios civiles o amenazas<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-20e509d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20e509d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eb31dde\" data-id=\"eb31dde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b80acfa elementor-widget elementor-widget-image\" data-id=\"b80acfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-4.png\" class=\"attachment-large size-large wp-image-5534\" alt=\"\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-4.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Global-Travel-Icon-4-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ea04ce3\" data-id=\"ea04ce3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f850be1 elementor-widget elementor-widget-text-editor\" data-id=\"f850be1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zonas prohibidas<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-41c7e24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41c7e24\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-36bb73d\" data-id=\"36bb73d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06f65ee elementor-align-left elementor-widget elementor-widget-global elementor-global-18522 elementor-global-4936 elementor-widget-button\" data-id=\"06f65ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/reedmackay.com\/es\/consulta-de-nuevo-negocio\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hable con un experto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5180b0c\" data-id=\"5180b0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4de016 elementor-align-left elementor-widget__width-initial elementor-widget elementor-widget-global elementor-global-18448 elementor-global-5271 elementor-widget-button\" data-id=\"e4de016\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/reedmackay.com\/es\/solicita-una-demostracion\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicite una demostraci\u00f3n gratuita<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3165591\" data-id=\"3165591\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-539bb31 elementor-widget elementor-widget-spacer\" data-id=\"539bb31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5f426d7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5f426d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2acfb8e\" data-id=\"2acfb8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8515ca6 elementor-widget elementor-widget-premium-counter\" data-id=\"8515ca6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"premium-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"premium-counter premium-counter-area top\" data-duration=\"3000\" data-from-value=\"0\" data-to-value=\"94\" data-delimiter=\",\" data-rounding=\"0\">\n\t\t\t\n\t\t<div class=\"premium-counter-icon\">\n\n\t\t\t<span class=\"icon\" data-animation=\"\">\n\n\t\t\t\t\t\t\t\t\t<div ><\/div>\n\t\t\t\t\n\t\t\t<\/span>\n\t\t<\/div>\n\n\t\t\n\t\t<div class=\"premium-init-wrapper column\">\n\n\t\t\t<div class=\"premium-counter-value-wrap\">\n\t\t\t\t\n\t\t\t\t<span class=\"premium-counter-init\" id=\"counter-8515ca6\">0<\/span>\n\n\t\t\t\t\t\t\t\t\t<span id=\"suffix\" class=\"counter-su-pre\">%<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5014ef2 elementor-widget elementor-widget-text-editor\" data-id=\"5014ef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El 94% de las veces nos ponemos en contacto con los clientes antes de que nos llamen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-657e307 elementor-widget elementor-widget-text-editor\" data-id=\"657e307\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si este es el nivel de servicio que espera, p\u00f3ngase en contacto con nosotros<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce2daa9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ce2daa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/reedmackay.com\/es\/contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hable con un experto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c34896e elementor-widget elementor-widget-heading\" data-id=\"c34896e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00e1s informaci\u00f3n. M\u00e1s informaci\u00f3n <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcbf5e0 premium-blog-align-left elementor-widget elementor-widget-premium-addon-blog\" data-id=\"bcbf5e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;premium_blog_columns_number&quot;:&quot;33.33%&quot;,&quot;premium_blog_grid&quot;:&quot;yes&quot;,&quot;premium_blog_layout&quot;:&quot;even&quot;,&quot;premium_blog_columns_number_tablet&quot;:&quot;50%&quot;,&quot;premium_blog_columns_number_mobile&quot;:&quot;100%&quot;}\" data-widget_type=\"premium-addon-blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\n\n\t\t\t\t<div class=\"premium-blog-wrap  premium-blog-even\" data-page=\"17642\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"58\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumb-effect-wrapper\">\n\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-container premium-blog-zoomin-effect\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"850\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/travel-regulations-2.png\" class=\"attachment-full size-full wp-image-43724\" alt=\"Passports and visas\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/travel-regulations-2.png 1080w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/travel-regulations-2-300x236.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/travel-regulations-2-1024x806.png 1024w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/03\/travel-regulations-2-768x604.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-overlay\">\n\t\t\t\t\t\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/reedmackay.com\/es\/whats-new-visas-and-travel-regulations\" target=\"_blank\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper \">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/whats-new-visas-and-travel-regulations\" target=\"_blank\">\n\t\t\t\tNovedades: visados y normas de viaje\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-categories premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-align-left fa-fw\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/category\/articulos-es\" rel=\"category tag\">Art\u00edculos<\/a>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"58\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/noticias-traslado-oficina-barcelona\" target=\"_blank\">\n\t\t\t\tReed &amp; Mackay traslada su oficina de Barcelona\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-categories premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-align-left fa-fw\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/category\/noticias-es\" rel=\"category tag\">Noticias<\/a>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"58\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumb-effect-wrapper\">\n\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-container premium-blog-zoomin-effect\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"850\" src=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/02\/Bleisure-1.png\" class=\"attachment-full size-full wp-image-38856\" alt=\"Bleisure travel trend\" srcset=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/02\/Bleisure-1.png 1080w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/02\/Bleisure-1-300x236.png 300w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/02\/Bleisure-1-1024x806.png 1024w, https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/02\/Bleisure-1-768x604.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-thumbnail-overlay\">\n\t\t\t\t\t\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/reedmackay.com\/es\/bleisure-travel-policies-everything-you-need-to-know\" target=\"_blank\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper \">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/bleisure-travel-policies-everything-you-need-to-know\" target=\"_blank\">\n\t\t\t\tViajes Bleisure: Todo lo que necesitas saber\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-categories premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-align-left fa-fw\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<a href=\"https:\/\/reedmackay.com\/es\/category\/articulos-es\" rel=\"category tag\">Art\u00edculos<\/a>\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gesti\u00f3n de reservas Seguridad para los viajeros Aprobaciones sencillas Gesti\u00f3n de gastos Informaci\u00f3n detallada Aplicaci\u00f3n m\u00f3vil Seguridad para los viajeros Localice a sus viajeros en cualquier momento, dondequiera que est\u00e9n. Le ayudamos a cuidar a su personal mediante el uso de una tecnolog\u00eda l\u00edder a nivel global respaldada por un servicio de emergencia en viajes.&hellip;&nbsp;<a href=\"https:\/\/reedmackay.com\/es\/bleisure-travel-policies-everything-you-need-to-know\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">Viajes Bleisure: Todo lo que necesitas saber<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":24159,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-17642","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seguridad para los viajeros | Reed &amp; Mackay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seguridad para los viajeros | Reed &amp; Mackay\" \/>\n<meta property=\"og:description\" content=\"Gesti\u00f3n de reservas Seguridad para los viajeros Aprobaciones sencillas Gesti\u00f3n de gastos Informaci\u00f3n detallada Aplicaci\u00f3n m\u00f3vil Seguridad para los viajeros Localice a sus viajeros en cualquier momento, dondequiera que est\u00e9n. Le ayudamos a cuidar a su personal mediante el uso de una tecnolog\u00eda l\u00edder a nivel global respaldada por un servicio de emergencia en viajes.&hellip;&nbsp;Leer m\u00e1s &raquo;Viajes Bleisure: Todo lo que necesitas saber\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros\" \/>\n<meta property=\"og:site_name\" content=\"Reed &amp; Mackay\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-26T10:41:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-6-2.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es\\\/seguridad-para-los-viajeros\",\"url\":\"https:\\\/\\\/reedmackay.com\\\/es\\\/seguridad-para-los-viajeros\",\"name\":\"Seguridad para los viajeros | Reed &amp; Mackay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es\\\/seguridad-para-los-viajeros#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es\\\/seguridad-para-los-viajeros#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reedmackay.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Reed-and-Mackay-Traveller-Safety-Corporate-Travel-App-1366-x-768px.jpg\",\"datePublished\":\"2023-12-13T15:06:32+00:00\",\"dateModified\":\"2024-01-26T10:41:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es\\\/seguridad-para-los-viajeros#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/reedmackay.com\\\/es\\\/seguridad-para-los-viajeros\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es\\\/seguridad-para-los-viajeros#primaryimage\",\"url\":\"https:\\\/\\\/reedmackay.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Reed-and-Mackay-Traveller-Safety-Corporate-Travel-App-1366-x-768px.jpg\",\"contentUrl\":\"https:\\\/\\\/reedmackay.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Reed-and-Mackay-Traveller-Safety-Corporate-Travel-App-1366-x-768px.jpg\",\"width\":1366,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es\\\/seguridad-para-los-viajeros#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/reedmackay.com\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seguridad para los viajeros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es#website\",\"url\":\"https:\\\/\\\/reedmackay.com\\\/es\",\"name\":\"Reed & Mackay\",\"description\":\"Reed and Mackay Travel and Events Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/reedmackay.com\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es#organization\",\"name\":\"Reed & Mackay\",\"url\":\"https:\\\/\\\/reedmackay.com\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/reedmackay.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/RM-Horz-Logo-Colour@2x.png\",\"contentUrl\":\"https:\\\/\\\/reedmackay.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/RM-Horz-Logo-Colour@2x.png\",\"width\":2107,\"height\":411,\"caption\":\"Reed & Mackay\"},\"image\":{\"@id\":\"https:\\\/\\\/reedmackay.com\\\/es#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seguridad para los viajeros | Reed &amp; Mackay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros","og_locale":"es_ES","og_type":"article","og_title":"Seguridad para los viajeros | Reed &amp; Mackay","og_description":"Gesti\u00f3n de reservas Seguridad para los viajeros Aprobaciones sencillas Gesti\u00f3n de gastos Informaci\u00f3n detallada Aplicaci\u00f3n m\u00f3vil Seguridad para los viajeros Localice a sus viajeros en cualquier momento, dondequiera que est\u00e9n. Le ayudamos a cuidar a su personal mediante el uso de una tecnolog\u00eda l\u00edder a nivel global respaldada por un servicio de emergencia en viajes.&hellip;&nbsp;Leer m\u00e1s &raquo;Viajes Bleisure: Todo lo que necesitas saber","og_url":"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros","og_site_name":"Reed &amp; Mackay","article_modified_time":"2024-01-26T10:41:46+00:00","og_image":[{"url":"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/12\/Reed-and-Mackay-Corporate-Travel-Management-Icon-6-2.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros","url":"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros","name":"Seguridad para los viajeros | Reed &amp; Mackay","isPartOf":{"@id":"https:\/\/reedmackay.com\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros#primaryimage"},"image":{"@id":"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros#primaryimage"},"thumbnailUrl":"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/01\/Reed-and-Mackay-Traveller-Safety-Corporate-Travel-App-1366-x-768px.jpg","datePublished":"2023-12-13T15:06:32+00:00","dateModified":"2024-01-26T10:41:46+00:00","breadcrumb":{"@id":"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros#primaryimage","url":"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/01\/Reed-and-Mackay-Traveller-Safety-Corporate-Travel-App-1366-x-768px.jpg","contentUrl":"https:\/\/reedmackay.com\/wp-content\/uploads\/2024\/01\/Reed-and-Mackay-Traveller-Safety-Corporate-Travel-App-1366-x-768px.jpg","width":1366,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/reedmackay.com\/es\/seguridad-para-los-viajeros#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/reedmackay.com\/es"},{"@type":"ListItem","position":2,"name":"Seguridad para los viajeros"}]},{"@type":"WebSite","@id":"https:\/\/reedmackay.com\/es#website","url":"https:\/\/reedmackay.com\/es","name":"Reed & Mackay","description":"Reed and Mackay Travel and Events Management","publisher":{"@id":"https:\/\/reedmackay.com\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reedmackay.com\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/reedmackay.com\/es#organization","name":"Reed & Mackay","url":"https:\/\/reedmackay.com\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/reedmackay.com\/es#\/schema\/logo\/image\/","url":"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/07\/RM-Horz-Logo-Colour@2x.png","contentUrl":"https:\/\/reedmackay.com\/wp-content\/uploads\/2023\/07\/RM-Horz-Logo-Colour@2x.png","width":2107,"height":411,"caption":"Reed & Mackay"},"image":{"@id":"https:\/\/reedmackay.com\/es#\/schema\/logo\/image\/"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/reedmackay.com\/es\/wp-json\/wp\/v2\/pages\/17642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reedmackay.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/reedmackay.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/reedmackay.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reedmackay.com\/es\/wp-json\/wp\/v2\/comments?post=17642"}],"version-history":[{"count":0,"href":"https:\/\/reedmackay.com\/es\/wp-json\/wp\/v2\/pages\/17642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reedmackay.com\/es\/wp-json\/wp\/v2\/media\/24159"}],"wp:attachment":[{"href":"https:\/\/reedmackay.com\/es\/wp-json\/wp\/v2\/media?parent=17642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}